{"id":18756,"date":"2024-07-26T00:30:50","date_gmt":"2024-07-26T00:30:50","guid":{"rendered":"https:\/\/wheelsem.com\/?p=18756"},"modified":"2025-05-14T15:30:16","modified_gmt":"2025-05-14T15:30:16","slug":"bustinza-goma-aporta-su-tecnologia-para-sembradoras","status":"publish","type":"post","link":"https:\/\/wheelsem.com\/de\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/","title":{"rendered":"Bustinza Goma bringt ihre Technologie f\u00fcr S\u00e4maschinen ein."},"content":{"rendered":"<p><strong>Junto a BASF y Wheelsem desarroll\u00f3 la primera rueda niveladora 100% reciclable. Est\u00e1 hecha con termopl\u00e1stico y suministra una serie de beneficios para el funcionamiento de las m\u00e1quinas.<\/strong><\/p>\n<p><a href=\"https:\/\/maquinac.com\/empresas\/bustinza-goma\/\">Bustinza Goma<\/a>\u00a0hace su aporte tecnol\u00f3gico para los nuevos equipamientos destinados a\u00a0<strong>sembradoras<\/strong>\u00a0que surgen en Argentina.<\/p>\n<p>La empresa santafesina particip\u00f3 junto a las compa\u00f1\u00edas\u00a0<strong>BASF<\/strong>\u00a0y\u00a0<strong>Wheelsem<\/strong>\u00a0en el desarrollo de la primera rueda niveladora para sembradoras, 100% reciclable<\/p>\n<p>El producto permite optimizar el trabajo de las m\u00e1quinas en condiciones desfavorables, aliviana el tren de sembrado y logra un menor consumo de combustible.<\/p>\n<p>Adem\u00e1s, la rueda es un termopl\u00e1stico, lo que la hace 100% reciclable, tanto dentro del mismo proceso de producci\u00f3n como luego de su vida \u00fatil, contribuyendo as\u00ed a la econom\u00eda circular.<\/p>\n<p>La innovaci\u00f3n fue premiada con una medalla de oro en la categor\u00eda siembra en la 8\u00b0 edici\u00f3n del\u00a0<strong>Premio Ternium Expoagro\u00a0<\/strong>a la Innovaci\u00f3n Agroindustrial.<\/p>\n<h4 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"17\" data-lineheight=\"25.5px\">Particularidades<\/h4>\n<p>La <strong>rueda niveladora<\/strong>\u00a0de termopl\u00e1stico, puede reciclarse durante el mismo proceso de producci\u00f3n de la rueda y tambi\u00e9n cuando ya cumpli\u00f3 su ciclo de trabajo.<\/p>\n<p>Esta innovaci\u00f3n reduce la huella de carbono ya que necesita menor energ\u00eda para producirse a diferencia de la rueda de metal, y aliviana sensiblemente todo el tren de la m\u00e1quina, lo que implica un ahorro en el uso de combustible.<\/p>\n<p>Otro beneficio es el mantenimiento, ya que posibilita un cambio r\u00e1pido de las ruedas de goma y los rodamientos.<\/p>\n<h4 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"17\" data-lineheight=\"25.5px\">Componentes<\/h4>\n<p>Desde\u00a0<strong>BASF Argentina<\/strong>\u00a0brindaron un grado de la poliamida\u00a0<strong>Ultramid<\/strong>\u00a0para la fabricaci\u00f3n de la rueda, que se destaca por su elevada resistencia mec\u00e1nica, rigidez y estabilidad t\u00e9rmica.<\/p>\n<p>La poliamida ofrece una gran resistencia a bajas temperaturas y la intemperie, un comportamiento favorable de fricci\u00f3n por deslizamiento y se puede procesar sin problema alguno.<\/p>\n<p>A su vez,\u00a0<a href=\"https:\/\/maquinac.com\/empresas\/bustinza-goma\/\">Bustinza Goma<\/a>\u00a0contribuy\u00f3 con su experiencia y tecnolog\u00eda en la producci\u00f3n de distintos elementos y partes para m\u00e1quinas agr\u00edcolas.<\/p>\n<p>En este caso, concret\u00f3 la fabricaci\u00f3n de la rueda niveladora con los materiales y los est\u00e1ndares suministrados por\u00a0<strong>BASF<\/strong>\u00a0y\u00a0<strong>Wheelsem<\/strong>.<\/p>\n<p>Fuente \/ Nota original: <a href=\"https:\/\/maquinac.com\/2024\/07\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/\">Bustinza Goma aporta su tecnolog\u00eda para sembradoras &#8211; Maquinac<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Junto a BASF y Wheelsem desarroll\u00f3 la primera rueda niveladora 100% reciclable. Est\u00e1 hecha con termopl\u00e1stico y suministra una serie de beneficios para el funcionamiento de las m\u00e1quinas. Bustinza Goma\u00a0hace su aporte tecnol\u00f3gico para los nuevos equipamientos destinados a\u00a0sembradoras\u00a0que surgen en Argentina. La empresa santafesina particip\u00f3 junto a las compa\u00f1\u00edas\u00a0BASF\u00a0y\u00a0Wheelsem\u00a0en el desarrollo de la primera&hellip;<\/p>","protected":false},"author":1,"featured_media":18758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","category-1","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bustinza Goma aporta su tecnolog\u00eda para sembradoras - Wheelsem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wheelsem.com\/de\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bustinza Goma aporta su tecnolog\u00eda para sembradoras - Wheelsem\" \/>\n<meta property=\"og:description\" content=\"Junto a BASF y Wheelsem desarroll\u00f3 la primera rueda niveladora 100% reciclable. Est\u00e1 hecha con termopl\u00e1stico y suministra una serie de beneficios para el funcionamiento de las m\u00e1quinas. Bustinza Goma\u00a0hace su aporte tecnol\u00f3gico para los nuevos equipamientos destinados a\u00a0sembradoras\u00a0que surgen en Argentina. La empresa santafesina particip\u00f3 junto a las compa\u00f1\u00edas\u00a0BASF\u00a0y\u00a0Wheelsem\u00a0en el desarrollo de la primera&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wheelsem.com\/de\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/\" \/>\n<meta property=\"og:site_name\" content=\"Wheelsem\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-26T00:30:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-14T15:30:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wheelsem.com\/wp-content\/uploads\/2025\/05\/Rueda-niveladora-para-sembradoras-wpv_900x450.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"colosimo101@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"colosimo101@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/\"},\"author\":{\"name\":\"colosimo101@gmail.com\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#\\\/schema\\\/person\\\/b005e81f0cf81aabbc8a84813fc7c364\"},\"headline\":\"Bustinza Goma aporta su tecnolog\u00eda para sembradoras\",\"datePublished\":\"2024-07-26T00:30:50+00:00\",\"dateModified\":\"2025-05-14T15:30:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/\"},\"wordCount\":378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Rueda-niveladora-para-sembradoras-wpv_900x450.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/\",\"name\":\"Bustinza Goma aporta su tecnolog\u00eda para sembradoras - Wheelsem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Rueda-niveladora-para-sembradoras-wpv_900x450.jpg\",\"datePublished\":\"2024-07-26T00:30:50+00:00\",\"dateModified\":\"2025-05-14T15:30:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Rueda-niveladora-para-sembradoras-wpv_900x450.jpg\",\"contentUrl\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Rueda-niveladora-para-sembradoras-wpv_900x450.jpg\",\"width\":675,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/wheelsem.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bustinza Goma aporta su tecnolog\u00eda para sembradoras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#website\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/\",\"name\":\"Wheelsem\",\"description\":\"Tecnolog\u00eda que marca la diferencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wheelsem.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#organization\",\"name\":\"Wheelsem\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-wheelsem.png\",\"contentUrl\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-wheelsem.png\",\"width\":1180,\"height\":643,\"caption\":\"Wheelsem\"},\"image\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#\\\/schema\\\/person\\\/b005e81f0cf81aabbc8a84813fc7c364\",\"name\":\"colosimo101@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g\",\"caption\":\"colosimo101@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/wheelsem.com\"],\"url\":\"https:\\\/\\\/wheelsem.com\\\/de\\\/author\\\/colosimo101gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bustinza Goma aporta su tecnolog\u00eda para sembradoras - Wheelsem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wheelsem.com\/de\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/","og_locale":"de_DE","og_type":"article","og_title":"Bustinza Goma aporta su tecnolog\u00eda para sembradoras - Wheelsem","og_description":"Junto a BASF y Wheelsem desarroll\u00f3 la primera rueda niveladora 100% reciclable. Est\u00e1 hecha con termopl\u00e1stico y suministra una serie de beneficios para el funcionamiento de las m\u00e1quinas. Bustinza Goma\u00a0hace su aporte tecnol\u00f3gico para los nuevos equipamientos destinados a\u00a0sembradoras\u00a0que surgen en Argentina. La empresa santafesina particip\u00f3 junto a las compa\u00f1\u00edas\u00a0BASF\u00a0y\u00a0Wheelsem\u00a0en el desarrollo de la primera&hellip;","og_url":"https:\/\/wheelsem.com\/de\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/","og_site_name":"Wheelsem","article_published_time":"2024-07-26T00:30:50+00:00","article_modified_time":"2025-05-14T15:30:16+00:00","og_image":[{"width":675,"height":450,"url":"http:\/\/wheelsem.com\/wp-content\/uploads\/2025\/05\/Rueda-niveladora-para-sembradoras-wpv_900x450.jpg","type":"image\/jpeg"}],"author":"colosimo101@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"colosimo101@gmail.com","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/#article","isPartOf":{"@id":"https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/"},"author":{"name":"colosimo101@gmail.com","@id":"https:\/\/wheelsem.com\/#\/schema\/person\/b005e81f0cf81aabbc8a84813fc7c364"},"headline":"Bustinza Goma aporta su tecnolog\u00eda para sembradoras","datePublished":"2024-07-26T00:30:50+00:00","dateModified":"2025-05-14T15:30:16+00:00","mainEntityOfPage":{"@id":"https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/"},"wordCount":378,"commentCount":0,"publisher":{"@id":"https:\/\/wheelsem.com\/#organization"},"image":{"@id":"https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/#primaryimage"},"thumbnailUrl":"https:\/\/wheelsem.com\/wp-content\/uploads\/2025\/05\/Rueda-niveladora-para-sembradoras-wpv_900x450.jpg","articleSection":["Uncategorized"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/","url":"https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/","name":"Bustinza Goma aporta su tecnolog\u00eda para sembradoras - Wheelsem","isPartOf":{"@id":"https:\/\/wheelsem.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/#primaryimage"},"image":{"@id":"https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/#primaryimage"},"thumbnailUrl":"https:\/\/wheelsem.com\/wp-content\/uploads\/2025\/05\/Rueda-niveladora-para-sembradoras-wpv_900x450.jpg","datePublished":"2024-07-26T00:30:50+00:00","dateModified":"2025-05-14T15:30:16+00:00","breadcrumb":{"@id":"https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/#primaryimage","url":"https:\/\/wheelsem.com\/wp-content\/uploads\/2025\/05\/Rueda-niveladora-para-sembradoras-wpv_900x450.jpg","contentUrl":"https:\/\/wheelsem.com\/wp-content\/uploads\/2025\/05\/Rueda-niveladora-para-sembradoras-wpv_900x450.jpg","width":675,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/wheelsem.com\/bustinza-goma-aporta-su-tecnologia-para-sembradoras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/wheelsem.com\/"},{"@type":"ListItem","position":2,"name":"Bustinza Goma aporta su tecnolog\u00eda para sembradoras"}]},{"@type":"WebSite","@id":"https:\/\/wheelsem.com\/#website","url":"https:\/\/wheelsem.com\/","name":"Wheelsem","description":"Tecnolog\u00eda que marca la diferencia","publisher":{"@id":"https:\/\/wheelsem.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wheelsem.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/wheelsem.com\/#organization","name":"Wheelsem","url":"https:\/\/wheelsem.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wheelsem.com\/#\/schema\/logo\/image\/","url":"https:\/\/wheelsem.com\/wp-content\/uploads\/2024\/05\/logo-wheelsem.png","contentUrl":"https:\/\/wheelsem.com\/wp-content\/uploads\/2024\/05\/logo-wheelsem.png","width":1180,"height":643,"caption":"Wheelsem"},"image":{"@id":"https:\/\/wheelsem.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wheelsem.com\/#\/schema\/person\/b005e81f0cf81aabbc8a84813fc7c364","name":"colosimo101@gmail.com","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g","caption":"colosimo101@gmail.com"},"sameAs":["https:\/\/wheelsem.com"],"url":"https:\/\/wheelsem.com\/de\/author\/colosimo101gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/wheelsem.com\/de\/wp-json\/wp\/v2\/posts\/18756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wheelsem.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wheelsem.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wheelsem.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wheelsem.com\/de\/wp-json\/wp\/v2\/comments?post=18756"}],"version-history":[{"count":3,"href":"https:\/\/wheelsem.com\/de\/wp-json\/wp\/v2\/posts\/18756\/revisions"}],"predecessor-version":[{"id":18896,"href":"https:\/\/wheelsem.com\/de\/wp-json\/wp\/v2\/posts\/18756\/revisions\/18896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wheelsem.com\/de\/wp-json\/wp\/v2\/media\/18758"}],"wp:attachment":[{"href":"https:\/\/wheelsem.com\/de\/wp-json\/wp\/v2\/media?parent=18756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wheelsem.com\/de\/wp-json\/wp\/v2\/categories?post=18756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wheelsem.com\/de\/wp-json\/wp\/v2\/tags?post=18756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}