{"id":18362,"date":"2024-10-15T14:33:36","date_gmt":"2024-10-15T14:33:36","guid":{"rendered":"https:\/\/wheelsem.com\/?p=18362"},"modified":"2025-05-14T15:32:14","modified_gmt":"2025-05-14T15:32:14","slug":"wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable","status":"publish","type":"post","link":"https:\/\/wheelsem.com\/ru\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/","title":{"rendered":"Wheelsem, BASF \u0438 Bustinza Goma \u043e\u0431\u044a\u0435\u0434\u0438\u043d\u044f\u044e\u0442 \u0443\u0441\u0438\u043b\u0438\u044f \u0432 \u043e\u0431\u043b\u0430\u0441\u0442\u0438 \u0443\u0441\u0442\u043e\u0439\u0447\u0438\u0432\u044b\u0445 \u0438\u043d\u043d\u043e\u0432\u0430\u0446\u0438\u0439 \u0434\u043b\u044f \u0440\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0438 \u043f\u0435\u0440\u0432\u043e\u0433\u043e \u043d\u0430 100% \u043f\u0435\u0440\u0435\u0440\u0430\u0431\u0430\u0442\u044b\u0432\u0430\u0435\u043c\u043e\u0433\u043e \u0432\u044b\u0440\u0430\u0432\u043d\u0438\u0432\u0430\u044e\u0449\u0435\u0433\u043e \u043a\u043e\u043b\u0435\u0441\u0430 \u0434\u043b\u044f \u0441\u0435\u044f\u043b\u043e\u043a."},"content":{"rendered":"<ul>\n<li><b>Esta creaci\u00f3n permite operar a las m\u00e1quinas sembradoras en condiciones desfavorables, aliviana el tren de sembrado y logra un menor consumo de combustible.<br \/>\n<\/b><\/li>\n<li><b>Adem\u00e1s, la rueda es un termopl\u00e1stico, lo que la hace 100% reciclable, tanto dentro del mismo proceso de producci\u00f3n como luego de su vida \u00fatil, contribuyendo as\u00ed a la econom\u00eda circular.<\/b><\/li>\n<li><b>La innovaci\u00f3n fue premiada con una medalla de oro en la categor\u00eda siembra en la 8\u00b0 edici\u00f3n del Premio Ternium Expoagro a la Innovaci\u00f3n Agroindustrial.<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><b>Buenos Aires, 23 de julio de 2024.<\/b>\u00a0Wheelsem, BASF y Bustinza Goma desarrollaron una rueda niveladora para sembradoras de termopl\u00e1stico que puede reciclarse durante el mismo proceso de producci\u00f3n de la rueda y tambi\u00e9n luego de su vida \u00fatil, contribuyendo as\u00ed a la econom\u00eda circular.<\/p>\n<p>Esta innovaci\u00f3n reduce la huella de carbono ya que necesita menor energ\u00eda para producirse a diferencia de la rueda de metal, y aliviana sensiblemente todo el tren de la m\u00e1quina, lo que implica un ahorro en el uso de combustible.<\/p>\n<p>Luciano Armoa, Socio Gerente de Wheelsem e ide\u00f3logo de la rueda niveladora, sostuvo que \u201centre los beneficios m\u00e1s importantes, en primer lugar, esta rueda permite operar a las sembradoras cuando las condiciones de suelo son muy desfavorables; el segundo beneficio es el mantenimiento, ya que es muy r\u00e1pido cambiar las ruedas de goma y los rodamientos. Y el tercero y \u00faltimo, es la vida \u00fatil del neum\u00e1tico, porque incrementa la vida \u00fatil del mismo porque no hay que estirarlo para colocarlo\u201d.<\/p>\n<p>Desde BASF Argentina, compa\u00f1\u00eda qu\u00edmica l\u00edder en innovaci\u00f3n y sustentabilidad, brindaron un grado de la poliamida Ultramid\u00ae para la fabricaci\u00f3n de la rueda, que se destaca por su elevada resistencia mec\u00e1nica, rigidez y estabilidad t\u00e9rmica. Esta poliamida ofrece una gran resistencia a bajas temperaturas y la intemperie, un comportamiento favorable de fricci\u00f3n por deslizamiento y se puede procesar sin problema alguno.<\/p>\n<p>En esa l\u00ednea, desde la compa\u00f1\u00eda qu\u00edmica acompa\u00f1aron el proceso con soporte t\u00e9cnico del equipo global de Ultrasim\u00ae, la herramienta tecnol\u00f3gica de simulaci\u00f3n para el dise\u00f1o ligero de BASF, ubicado en Alemania, quienes proveyeron las informaciones espec\u00edficas para el dise\u00f1o de la rueda y la simulaci\u00f3n de la vida \u00fatil de la misma. Adem\u00e1s, particip\u00f3 del desarrollo el equipo t\u00e9cnico regional de la divisi\u00f3n Materiales de Performance de BASF, localizado en Brasil.<\/p>\n<p>En ese sentido, Florencia Muratori, gerente de la divisi\u00f3n Materiales de Performance de BASF para Argentina, Bolivia, Paraguay y Uruguay, explic\u00f3: \u201cDesde BASF estamos muy orgullosos de unirnos a Wheelsem y a Bustinza Goma, brindando nuestra poliamida Ultramid\u00ae y acompa\u00f1ando con el conocimiento t\u00e9cnico de nuestros equipos de Argentina, Brasil y Alemania\u201d, y concluyo: \u201cComo parte de nuestra estrategia hacia un futuro m\u00e1s sustentable, apoyamos a nuestros clientes y socios hacia la transformaci\u00f3n verde, y con esta soluci\u00f3n tambi\u00e9n contribuimos a la econom\u00eda circular para el sector agroindustrial, combinando sustentabilidad e innovaci\u00f3n\u201d.<\/p>\n<p><b>Premio Ternium Expoagro a la Innovaci\u00f3n Agroindustrial<\/b><\/p>\n<p>Adem\u00e1s, la rueda niveladora recibi\u00f3 una medalla de oro en el rubro siembra en la 8\u00b0 edici\u00f3n del Premio Ternium Expoagro a la Innovaci\u00f3n Agroindustrial, que destaca y estimula la incorporaci\u00f3n de tecnolog\u00eda en la maquinaria argentina, y potencia la competitividad internacional alentando la mejora continua de sus procesos de producci\u00f3n.<\/p>\n<p>\u201cEste premio es m\u00e9rito de la innovaci\u00f3n y es el reconocimiento a que vamos por el bueno camino\u201d, destac\u00f3 Luciano Armoa. La rueda niveladora est\u00e1 pensada para ser utilizada en todo el mundo, y ya cuenta con patentes en Argentina, Brasil, Estados Unidos y varios pa\u00edses de Europa, entre otros.<\/p>\n<p>Fuente \/ Nota original: <a href=\"https:\/\/www.basf.com\/ar\/es\/media\/news-releases\/2024\/julio\/wheelsem--basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sust\">Wheelsem, BASF \u0438 Bustinza Goma \u043e\u0431\u044a\u0435\u0434\u0438\u043d\u044f\u044e\u0442 \u0443\u0441\u0438\u043b\u0438\u044f \u0432 \u043e\u0431\u043b\u0430\u0441\u0442\u0438 \u0443\u0441\u0442\u043e\u0439\u0447\u0438\u0432\u044b\u0445 \u0438\u043d\u043d\u043e\u0432\u0430\u0446\u0438\u0439 \u0434\u043b\u044f \u0440\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0438 \u043f\u0435\u0440\u0432\u043e\u0433\u043e \u043d\u0430 100% \u043f\u0435\u0440\u0435\u0440\u0430\u0431\u0430\u0442\u044b\u0432\u0430\u0435\u043c\u043e\u0433\u043e \u0432\u044b\u0440\u0430\u0432\u043d\u0438\u0432\u0430\u044e\u0449\u0435\u0433\u043e \u043a\u043e\u043b\u0435\u0441\u0430 \u0434\u043b\u044f \u0441\u0435\u044f\u043b\u043e\u043a.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Esta creaci\u00f3n permite operar a las m\u00e1quinas sembradoras en condiciones desfavorables, aliviana el tren de sembrado y logra un menor consumo de combustible. Adem\u00e1s, la rueda es un termopl\u00e1stico, lo que la hace 100% reciclable, tanto dentro del mismo proceso de producci\u00f3n como luego de su vida \u00fatil, contribuyendo as\u00ed a la econom\u00eda circular. La&hellip;<\/p>","protected":false},"author":1,"featured_media":18715,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","category-1","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wheelsem, BASF y Bustinza Goma unen esfuerzos en innovaci\u00f3n sustentable para el desarrollo de la primera rueda niveladora para sembradoras 100% reciclable - Wheelsem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wheelsem.com\/ru\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wheelsem, BASF y Bustinza Goma unen esfuerzos en innovaci\u00f3n sustentable para el desarrollo de la primera rueda niveladora para sembradoras 100% reciclable - Wheelsem\" \/>\n<meta property=\"og:description\" content=\"Esta creaci\u00f3n permite operar a las m\u00e1quinas sembradoras en condiciones desfavorables, aliviana el tren de sembrado y logra un menor consumo de combustible. Adem\u00e1s, la rueda es un termopl\u00e1stico, lo que la hace 100% reciclable, tanto dentro del mismo proceso de producci\u00f3n como luego de su vida \u00fatil, contribuyendo as\u00ed a la econom\u00eda circular. La&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wheelsem.com\/ru\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/\" \/>\n<meta property=\"og:site_name\" content=\"Wheelsem\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-15T14:33:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-14T15:32:14+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wheelsem.com\/wp-content\/uploads\/2024\/05\/0ce3dbf3-48ad-4bcd-80f8-c6bc6ac5a399.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"colosimo101@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c\" \/>\n\t<meta name=\"twitter:data1\" content=\"colosimo101@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u043c\u0438\u043d\u0443\u0442\u044b\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/\"},\"author\":{\"name\":\"colosimo101@gmail.com\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#\\\/schema\\\/person\\\/b005e81f0cf81aabbc8a84813fc7c364\"},\"headline\":\"Wheelsem, BASF y Bustinza Goma unen esfuerzos en innovaci\u00f3n sustentable para el desarrollo de la primera rueda niveladora para sembradoras 100% reciclable\",\"datePublished\":\"2024-10-15T14:33:36+00:00\",\"dateModified\":\"2025-05-14T15:32:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/\"},\"wordCount\":683,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/0ce3dbf3-48ad-4bcd-80f8-c6bc6ac5a399.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/\",\"name\":\"Wheelsem, BASF y Bustinza Goma unen esfuerzos en innovaci\u00f3n sustentable para el desarrollo de la primera rueda niveladora para sembradoras 100% reciclable - Wheelsem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/0ce3dbf3-48ad-4bcd-80f8-c6bc6ac5a399.jpg\",\"datePublished\":\"2024-10-15T14:33:36+00:00\",\"dateModified\":\"2025-05-14T15:32:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/0ce3dbf3-48ad-4bcd-80f8-c6bc6ac5a399.jpg\",\"contentUrl\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/0ce3dbf3-48ad-4bcd-80f8-c6bc6ac5a399.jpg\",\"width\":2000,\"height\":1334},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/wheelsem.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wheelsem, BASF y Bustinza Goma unen esfuerzos en innovaci\u00f3n sustentable para el desarrollo de la primera rueda niveladora para sembradoras 100% reciclable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#website\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/\",\"name\":\"Wheelsem\",\"description\":\"Tecnolog\u00eda que marca la diferencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wheelsem.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#organization\",\"name\":\"Wheelsem\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-wheelsem.png\",\"contentUrl\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-wheelsem.png\",\"width\":1180,\"height\":643,\"caption\":\"Wheelsem\"},\"image\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#\\\/schema\\\/person\\\/b005e81f0cf81aabbc8a84813fc7c364\",\"name\":\"colosimo101@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g\",\"caption\":\"colosimo101@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/wheelsem.com\"],\"url\":\"https:\\\/\\\/wheelsem.com\\\/ru\\\/author\\\/colosimo101gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wheelsem, BASF y Bustinza Goma unen esfuerzos en innovaci\u00f3n sustentable para el desarrollo de la primera rueda niveladora para sembradoras 100% reciclable - Wheelsem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wheelsem.com\/ru\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/","og_locale":"ru_RU","og_type":"article","og_title":"Wheelsem, BASF y Bustinza Goma unen esfuerzos en innovaci\u00f3n sustentable para el desarrollo de la primera rueda niveladora para sembradoras 100% reciclable - Wheelsem","og_description":"Esta creaci\u00f3n permite operar a las m\u00e1quinas sembradoras en condiciones desfavorables, aliviana el tren de sembrado y logra un menor consumo de combustible. Adem\u00e1s, la rueda es un termopl\u00e1stico, lo que la hace 100% reciclable, tanto dentro del mismo proceso de producci\u00f3n como luego de su vida \u00fatil, contribuyendo as\u00ed a la econom\u00eda circular. La&hellip;","og_url":"https:\/\/wheelsem.com\/ru\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/","og_site_name":"Wheelsem","article_published_time":"2024-10-15T14:33:36+00:00","article_modified_time":"2025-05-14T15:32:14+00:00","og_image":[{"width":2000,"height":1334,"url":"http:\/\/wheelsem.com\/wp-content\/uploads\/2024\/05\/0ce3dbf3-48ad-4bcd-80f8-c6bc6ac5a399.jpg","type":"image\/jpeg"}],"author":"colosimo101@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c":"colosimo101@gmail.com","\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"3 \u043c\u0438\u043d\u0443\u0442\u044b"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/#article","isPartOf":{"@id":"https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/"},"author":{"name":"colosimo101@gmail.com","@id":"https:\/\/wheelsem.com\/#\/schema\/person\/b005e81f0cf81aabbc8a84813fc7c364"},"headline":"Wheelsem, BASF y Bustinza Goma unen esfuerzos en innovaci\u00f3n sustentable para el desarrollo de la primera rueda niveladora para sembradoras 100% reciclable","datePublished":"2024-10-15T14:33:36+00:00","dateModified":"2025-05-14T15:32:14+00:00","mainEntityOfPage":{"@id":"https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/"},"wordCount":683,"commentCount":0,"publisher":{"@id":"https:\/\/wheelsem.com\/#organization"},"image":{"@id":"https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/#primaryimage"},"thumbnailUrl":"https:\/\/wheelsem.com\/wp-content\/uploads\/2024\/05\/0ce3dbf3-48ad-4bcd-80f8-c6bc6ac5a399.jpg","articleSection":["Uncategorized"],"inLanguage":"ru-RU","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/","url":"https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/","name":"Wheelsem, BASF y Bustinza Goma unen esfuerzos en innovaci\u00f3n sustentable para el desarrollo de la primera rueda niveladora para sembradoras 100% reciclable - Wheelsem","isPartOf":{"@id":"https:\/\/wheelsem.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/#primaryimage"},"image":{"@id":"https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/#primaryimage"},"thumbnailUrl":"https:\/\/wheelsem.com\/wp-content\/uploads\/2024\/05\/0ce3dbf3-48ad-4bcd-80f8-c6bc6ac5a399.jpg","datePublished":"2024-10-15T14:33:36+00:00","dateModified":"2025-05-14T15:32:14+00:00","breadcrumb":{"@id":"https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/#primaryimage","url":"https:\/\/wheelsem.com\/wp-content\/uploads\/2024\/05\/0ce3dbf3-48ad-4bcd-80f8-c6bc6ac5a399.jpg","contentUrl":"https:\/\/wheelsem.com\/wp-content\/uploads\/2024\/05\/0ce3dbf3-48ad-4bcd-80f8-c6bc6ac5a399.jpg","width":2000,"height":1334},{"@type":"BreadcrumbList","@id":"https:\/\/wheelsem.com\/wheelsem-basf-y-bustinza-goma-unen-esfuerzos-en-innovacion-sustentable-para-el-desarrollo-de-la-primera-rueda-niveladora-para-sembradoras-100-reciclable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/wheelsem.com\/"},{"@type":"ListItem","position":2,"name":"Wheelsem, BASF y Bustinza Goma unen esfuerzos en innovaci\u00f3n sustentable para el desarrollo de la primera rueda niveladora para sembradoras 100% reciclable"}]},{"@type":"WebSite","@id":"https:\/\/wheelsem.com\/#website","url":"https:\/\/wheelsem.com\/","name":"Wheelsem","description":"Tecnolog\u00eda que marca la diferencia","publisher":{"@id":"https:\/\/wheelsem.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wheelsem.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/wheelsem.com\/#organization","name":"Wheelsem","url":"https:\/\/wheelsem.com\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/wheelsem.com\/#\/schema\/logo\/image\/","url":"https:\/\/wheelsem.com\/wp-content\/uploads\/2024\/05\/logo-wheelsem.png","contentUrl":"https:\/\/wheelsem.com\/wp-content\/uploads\/2024\/05\/logo-wheelsem.png","width":1180,"height":643,"caption":"Wheelsem"},"image":{"@id":"https:\/\/wheelsem.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wheelsem.com\/#\/schema\/person\/b005e81f0cf81aabbc8a84813fc7c364","name":"colosimo101@gmail.com","image":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/secure.gravatar.com\/avatar\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g","caption":"colosimo101@gmail.com"},"sameAs":["https:\/\/wheelsem.com"],"url":"https:\/\/wheelsem.com\/ru\/author\/colosimo101gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/wheelsem.com\/ru\/wp-json\/wp\/v2\/posts\/18362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wheelsem.com\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wheelsem.com\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wheelsem.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wheelsem.com\/ru\/wp-json\/wp\/v2\/comments?post=18362"}],"version-history":[{"count":5,"href":"https:\/\/wheelsem.com\/ru\/wp-json\/wp\/v2\/posts\/18362\/revisions"}],"predecessor-version":[{"id":18898,"href":"https:\/\/wheelsem.com\/ru\/wp-json\/wp\/v2\/posts\/18362\/revisions\/18898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wheelsem.com\/ru\/wp-json\/wp\/v2\/media\/18715"}],"wp:attachment":[{"href":"https:\/\/wheelsem.com\/ru\/wp-json\/wp\/v2\/media?parent=18362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wheelsem.com\/ru\/wp-json\/wp\/v2\/categories?post=18362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wheelsem.com\/ru\/wp-json\/wp\/v2\/tags?post=18362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}