{"id":18366,"date":"2023-11-28T14:35:26","date_gmt":"2023-11-28T14:35:26","guid":{"rendered":"https:\/\/wheelsem.com\/?p=18366"},"modified":"2025-05-14T15:31:54","modified_gmt":"2025-05-14T15:31:54","slug":"innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro","status":"publish","type":"post","link":"https:\/\/wheelsem.com\/uk\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/","title":{"rendered":"\u0410\u0433\u0440\u043e\u043f\u0440\u043e\u043c\u0438\u0441\u043b\u043e\u0432\u0430 \u0456\u043d\u043d\u043e\u0432\u0430\u0446\u0456\u044f: 9 \u0442\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0456\u0439, \u0449\u043e \u043e\u0442\u0440\u0438\u043c\u0430\u043b\u0438 \u043c\u0435\u0434\u0430\u043b\u0456 \u043d\u0430 \u043f\u0440\u0435\u043c\u0456\u0457 Ternium Expoagro."},"content":{"rendered":"<div class=\"bloque_superior_nota\">\n<h2>Se conocieron los proyectos elegidos por el jurado entre un total de 40 presentados, y que recibir\u00e1n sus galardones durante la pr\u00f3xima edici\u00f3n de Expoagro.<\/h2>\n<\/div>\n<div class=\"seccion_top clearfix\">\n<div class=\"notas-top\">\n<div id=\"laNota\" class=\"nota\">\n<div class=\"imagen\">\n<p>Las mejores innovaciones agroindustriales de 2023 ya fueron elegidas: la empresa Ternium, Expoagro y la Sociedad Alemana de Agricultura (DLG) dieron a conocer el listado de ganadores en el marco de los Premios Ternium Expoagro a la Innovaci\u00f3n Agroindustrial.<\/p>\n<p>Seg\u00fan informaron desde Expoagro, se recibieron un total de 40 desarrollos que aspiraban a ser elegidos y finalmente se escogieron 9 que recibir\u00e1n una medalla durante la pr\u00f3xima edici\u00f3n de Expoagro, del 5 al 8 de marzo de 2024 en San Nicol\u00e1s.<\/p>\n<p>LOS PREMIOS TERNIUM EXPOAGRO<br \/>\nEn concreto, los desarrollos seleccionados fueron los siguientes:<\/p>\n<p>Medallas de oro<br \/>\nCosechadora basada en cabezal desgranador: una idea de la firma G-FAS SAS, que particip\u00f3 en el rubro cosecha.<\/p>\n<p><strong>Rueda niveladora de profundidad con alabes:<\/strong>\u00a0de la empresa Wheelsem, en el rubro siembra.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-18480\" src=\"https:\/\/wheelsem.com\/wp-content\/uploads\/2025\/04\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1-285x300.jpg\" alt=\"\" width=\"285\" height=\"300\" srcset=\"https:\/\/wheelsem.com\/wp-content\/uploads\/2025\/04\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1-285x300.jpg 285w, https:\/\/wheelsem.com\/wp-content\/uploads\/2025\/04\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1-768x807.jpg 768w, https:\/\/wheelsem.com\/wp-content\/uploads\/2025\/04\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1.jpg 974w\" sizes=\"(max-width: 285px) 100vw, 285px\" \/><\/p>\n<h3><strong>Medallas de plata<\/strong><\/h3>\n<ul>\n<li><strong>Extractora de grano con bobinador eyector<\/strong>\u00a0(empresa Richiger, rubro post cosecha)<\/li>\n<li><strong>Tolva 4 ruedas directrices<\/strong>\u00a0(Cestari, post cosecha)<\/li>\n<li><strong>Sistema de medici\u00f3n y c\u00e1lculo de autonom\u00eda para siembra en semillas y fertilizantes<\/strong>\u00a0(Leaf Agrotronic, siembra)<\/li>\n<\/ul>\n<h3><strong>Medallas de bronce<\/strong><\/h3>\n<ul>\n<li><strong>Sistema de accionamiento seguro del tubo de descarg<\/strong>a (Cestari, post cosecha)<\/li>\n<li><strong>Sistema de corte l\u00ednea a l\u00ednea para sembradoras de transmisi\u00f3n mec\u00e1nica<\/strong>\u00a0(desarrollo en conjunto entre Leaf, Crucianelli y Oripon, del rubro siembra)<\/li>\n<li><strong>Riego solar m\u00f3vil<\/strong>\u00a0(Green Valley Solar, rubro Energ\u00edas Renovables y Eficiencia Energ\u00e9tica)<\/li>\n<\/ul>\n<p>Asimismo, los juradores decidieron otorgar las siguientes<strong>\u00a0menciones especiales<\/strong>:<\/p>\n<ul>\n<li><strong>Control el\u00e9ctrico de malezas:<\/strong>\u00a0menci\u00f3n en sistemas alternativos para control de adversidades, para la empresa Agritech, en el rubro protecci\u00f3n vegetal.<\/li>\n<li><strong>Sembradora air drill autotransportable:<\/strong>\u00a0menci\u00f3n al dise\u00f1o industrial, en el rubro siembra, para la compa\u00f1\u00eda Agrometal.<\/li>\n<li><a href=\"https:\/\/www.infocampo.com.ar\/como-funciona-velosofia-un-servicio-para-alquilar-sembradoras-super-tecnologicas\/\"><strong>Velosof\u00eda<\/strong><\/a>: menci\u00f3n en nuevos modelos de negocio, para la firma Plantium, en el rubro siembra.<\/li>\n<li><strong>Determinaci\u00f3n de variedades y calidad f\u00edsica de granos mediante inteligencia artificial:<\/strong>\u00a0menci\u00f3n a buenas pr\u00e1cticas agr\u00edcolas, en el rubro post cosecha, para la empresa MOQ.<\/li>\n<\/ul>\n<h2><strong>HABLAN LOS JURADOS<\/strong><\/h2>\n<p>Respecto de la elecci\u00f3n de estos desarrollos y el concurso en general, uno de los jurados, Hern\u00e1n Ferrari, remarc\u00f3: \u201c<strong>Estoy muy contento por la cantidad de innovaciones<\/strong>\u00a0que se desarrollan en el pa\u00eds y el impacto que esto va a traer, no solo a nivel nacional sino en el mundo\u201d.<\/p>\n<blockquote><p>\u201cCuando hablamos de que Argentina va a ser uno de los grandes responsables de alimentar el mundo y ver que ser\u00e1 acompa\u00f1ado por\u00a0<strong>Inteligencia Artificial, rob\u00f3tica, y mecanizaci\u00f3n de \u00faltima tecnolog\u00eda,<\/strong>\u00a0da mucha esperanza de lograr alimentar al mundo con la tecnolog\u00eda desarrollada en Argentina\u201d, mencion\u00f3.<\/p><\/blockquote>\n<p>En similar sentido, Pablo Petit, de la Facultad de Ciencias Agrarias de la Universidad Nacional de C\u00f3rdoba, opin\u00f3: \u201c<strong>Me sorprendi\u00f3 el nivel de los proyectos que se presentaron.<\/strong>\u00a0Las empresas trabajan e invierten mucho en desarrollos\u201d.<\/p>\n<p>Desde su punto de vista, \u201cel acompa\u00f1amiento que reciben de este tipo de premios es un gran beneficio. Por un lado, para impulsar los proyectos en los que est\u00e1n trabajando, y por el otro,<strong>\u00a0darle un valor a ese proyecto para que se transforme en un producto que llegue al campo<\/strong>, al productor, que tenga un impacto en la producci\u00f3n y que tambi\u00e9n traiga un beneficio para la regi\u00f3n y para el pa\u00eds\u201d.<\/p>\n<p>Desde Alemania, en tanto, Thomas Rademacher, parte del jurado por la Universidad de Bingen, valor\u00f3: \u201c<strong>Los nuevos desarrollos en las m\u00e1quinas para Siembra Directa son siempre asombrosos: t\u00e9cnicas para una mejor adaptaci\u00f3n al suelo y control de profundidad.<\/strong>\u00a0Es notable que los ingenieros de desarrollo trabajan con la tecnolog\u00eda en el campo y la mejoran a\u00fan m\u00e1s bas\u00e1ndose en estos hallazgos\u201d.<\/p>\n<p>Cabe recordar que la DLG es organizadora de\u00a0<strong><a href=\"https:\/\/www.infocampo.com.ar\/tag\/agritechnica\/\">Agritechnica<\/a><\/strong>, que tambi\u00e9n entrega medallas a las mejores innovaciones agroindustriales que se desarrollan en Europa y otras partes del mundo.<\/p>\n<p>Este a\u00f1o, la medalla de oro fue otorgada a la\u00a0<strong>nueva cosechadora CR11 de New Holland<\/strong>, que es la m\u00e1s grande del mundo.<\/p>\n<p>En este marco, cabe destacar que las tecnolog\u00edas que lograron una Medalla de Oro podr\u00e1n contar con un espacio en Expoagro 2025.\u00a0<strong>Adem\u00e1s, la DLG podr\u00e1 elegir uno de los desarrollos triunfadores para ser presentado en la feria Agritechnica<\/strong>, que se realiz\u00f3 recientemente en Hannover (Alemania) y volver\u00e1 a tener lugar en 2025.<\/p>\n<p>Adem\u00e1s de los jurados mencionados, los otros que participaron del grupo de expertos fueron: Gabriel Tinghitella (CREA), Luis Negruchi (AAPRESID), H\u00e9ctor Huergo (CLAR\u00cdN RURAL), Telmo Palancar (UNIVERSIDAD NACIONAL DE LA PLATA), Sergio Marinelli (FACMA), Roberto Del Castagner (UNIVERSIDAD NACIONAL DE RIO CUARTO), Marcelo Amado (UNIVERSIDAD NACIONAL DE BUENOS AIRES), Alejandro Cl\u00e9rici (CIDETER), Juan Raggio (Asesor privado) y Silvio Zurzolo (UNI\u00d3N INDSUTRIAL ARGENTINA).<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Fuente \/ Nota original: <a href=\"https:\/\/www.infocampo.com.ar\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/\">Innovaci\u00f3n agroindustrial: las 9 tecnolog\u00edas que se llevaron medallas en los premios Ternium Expoagro &#8211; Infocampo<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Se conocieron los proyectos elegidos por el jurado entre un total de 40 presentados, y que recibir\u00e1n sus galardones durante la pr\u00f3xima edici\u00f3n de Expoagro. Las mejores innovaciones agroindustriales de 2023 ya fueron elegidas: la empresa Ternium, Expoagro y la Sociedad Alemana de Agricultura (DLG) dieron a conocer el listado de ganadores en el marco&hellip;<\/p>","protected":false},"author":1,"featured_media":18480,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","category-1","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Innovaci\u00f3n agroindustrial: las 9 tecnolog\u00edas que se llevaron medallas en los premios Ternium Expoagro - Wheelsem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wheelsem.com\/uk\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/\" \/>\n<meta property=\"og:locale\" content=\"uk_UA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Innovaci\u00f3n agroindustrial: las 9 tecnolog\u00edas que se llevaron medallas en los premios Ternium Expoagro - Wheelsem\" \/>\n<meta property=\"og:description\" content=\"Se conocieron los proyectos elegidos por el jurado entre un total de 40 presentados, y que recibir\u00e1n sus galardones durante la pr\u00f3xima edici\u00f3n de Expoagro. Las mejores innovaciones agroindustriales de 2023 ya fueron elegidas: la empresa Ternium, Expoagro y la Sociedad Alemana de Agricultura (DLG) dieron a conocer el listado de ganadores en el marco&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wheelsem.com\/uk\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/\" \/>\n<meta property=\"og:site_name\" content=\"Wheelsem\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-28T14:35:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-14T15:31:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/wheelsem.com\/wp-content\/uploads\/2025\/04\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"974\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"colosimo101@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e\" \/>\n\t<meta name=\"twitter:data1\" content=\"colosimo101@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u041f\u0440\u0438\u0431\u043b. \u0447\u0430\u0441 \u0447\u0438\u0442\u0430\u043d\u043d\u044f\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 \u0445\u0432\u0438\u043b\u0438\u043d\u0438\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/\"},\"author\":{\"name\":\"colosimo101@gmail.com\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#\\\/schema\\\/person\\\/b005e81f0cf81aabbc8a84813fc7c364\"},\"headline\":\"Innovaci\u00f3n agroindustrial: las 9 tecnolog\u00edas que se llevaron medallas en los premios Ternium Expoagro\",\"datePublished\":\"2023-11-28T14:35:26+00:00\",\"dateModified\":\"2025-05-14T15:31:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/\"},\"wordCount\":849,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"uk\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/\",\"name\":\"Innovaci\u00f3n agroindustrial: las 9 tecnolog\u00edas que se llevaron medallas en los premios Ternium Expoagro - Wheelsem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1.jpg\",\"datePublished\":\"2023-11-28T14:35:26+00:00\",\"dateModified\":\"2025-05-14T15:31:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/#breadcrumb\"},\"inLanguage\":\"uk\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"uk\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1.jpg\",\"contentUrl\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1.jpg\",\"width\":974,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/wheelsem.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Innovaci\u00f3n agroindustrial: las 9 tecnolog\u00edas que se llevaron medallas en los premios Ternium Expoagro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#website\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/\",\"name\":\"Wheelsem\",\"description\":\"Tecnolog\u00eda que marca la diferencia\",\"publisher\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wheelsem.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"uk\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#organization\",\"name\":\"Wheelsem\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"uk\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-wheelsem.png\",\"contentUrl\":\"https:\\\/\\\/wheelsem.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-wheelsem.png\",\"width\":1180,\"height\":643,\"caption\":\"Wheelsem\"},\"image\":{\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wheelsem.com\\\/#\\\/schema\\\/person\\\/b005e81f0cf81aabbc8a84813fc7c364\",\"name\":\"colosimo101@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"uk\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g\",\"caption\":\"colosimo101@gmail.com\"},\"sameAs\":[\"https:\\\/\\\/wheelsem.com\"],\"url\":\"https:\\\/\\\/wheelsem.com\\\/uk\\\/author\\\/colosimo101gmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Innovaci\u00f3n agroindustrial: las 9 tecnolog\u00edas que se llevaron medallas en los premios Ternium Expoagro - Wheelsem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wheelsem.com\/uk\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/","og_locale":"uk_UA","og_type":"article","og_title":"Innovaci\u00f3n agroindustrial: las 9 tecnolog\u00edas que se llevaron medallas en los premios Ternium Expoagro - Wheelsem","og_description":"Se conocieron los proyectos elegidos por el jurado entre un total de 40 presentados, y que recibir\u00e1n sus galardones durante la pr\u00f3xima edici\u00f3n de Expoagro. Las mejores innovaciones agroindustriales de 2023 ya fueron elegidas: la empresa Ternium, Expoagro y la Sociedad Alemana de Agricultura (DLG) dieron a conocer el listado de ganadores en el marco&hellip;","og_url":"https:\/\/wheelsem.com\/uk\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/","og_site_name":"Wheelsem","article_published_time":"2023-11-28T14:35:26+00:00","article_modified_time":"2025-05-14T15:31:54+00:00","og_image":[{"width":974,"height":1024,"url":"http:\/\/wheelsem.com\/wp-content\/uploads\/2025\/04\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1.jpg","type":"image\/jpeg"}],"author":"colosimo101@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e":"colosimo101@gmail.com","\u041f\u0440\u0438\u0431\u043b. \u0447\u0430\u0441 \u0447\u0438\u0442\u0430\u043d\u043d\u044f":"4 \u0445\u0432\u0438\u043b\u0438\u043d\u0438"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/#article","isPartOf":{"@id":"https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/"},"author":{"name":"colosimo101@gmail.com","@id":"https:\/\/wheelsem.com\/#\/schema\/person\/b005e81f0cf81aabbc8a84813fc7c364"},"headline":"Innovaci\u00f3n agroindustrial: las 9 tecnolog\u00edas que se llevaron medallas en los premios Ternium Expoagro","datePublished":"2023-11-28T14:35:26+00:00","dateModified":"2025-05-14T15:31:54+00:00","mainEntityOfPage":{"@id":"https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/"},"wordCount":849,"commentCount":0,"publisher":{"@id":"https:\/\/wheelsem.com\/#organization"},"image":{"@id":"https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/#primaryimage"},"thumbnailUrl":"https:\/\/wheelsem.com\/wp-content\/uploads\/2025\/04\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1.jpg","articleSection":["Uncategorized"],"inLanguage":"uk","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/","url":"https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/","name":"Innovaci\u00f3n agroindustrial: las 9 tecnolog\u00edas que se llevaron medallas en los premios Ternium Expoagro - Wheelsem","isPartOf":{"@id":"https:\/\/wheelsem.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/#primaryimage"},"image":{"@id":"https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/#primaryimage"},"thumbnailUrl":"https:\/\/wheelsem.com\/wp-content\/uploads\/2025\/04\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1.jpg","datePublished":"2023-11-28T14:35:26+00:00","dateModified":"2025-05-14T15:31:54+00:00","breadcrumb":{"@id":"https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/#breadcrumb"},"inLanguage":"uk","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/"]}]},{"@type":"ImageObject","inLanguage":"uk","@id":"https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/#primaryimage","url":"https:\/\/wheelsem.com\/wp-content\/uploads\/2025\/04\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1.jpg","contentUrl":"https:\/\/wheelsem.com\/wp-content\/uploads\/2025\/04\/Descargar-imagen-de-desarrollo-de-Wheelsem-974x1024-1.jpg","width":974,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/wheelsem.com\/innovacion-agroindustrial-las-9-tecnologias-que-se-llevaron-medallas-en-los-premios-ternium-expoagro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/wheelsem.com\/"},{"@type":"ListItem","position":2,"name":"Innovaci\u00f3n agroindustrial: las 9 tecnolog\u00edas que se llevaron medallas en los premios Ternium Expoagro"}]},{"@type":"WebSite","@id":"https:\/\/wheelsem.com\/#website","url":"https:\/\/wheelsem.com\/","name":"Wheelsem","description":"Tecnolog\u00eda que marca la diferencia","publisher":{"@id":"https:\/\/wheelsem.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wheelsem.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"uk"},{"@type":"Organization","@id":"https:\/\/wheelsem.com\/#organization","name":"Wheelsem","url":"https:\/\/wheelsem.com\/","logo":{"@type":"ImageObject","inLanguage":"uk","@id":"https:\/\/wheelsem.com\/#\/schema\/logo\/image\/","url":"https:\/\/wheelsem.com\/wp-content\/uploads\/2024\/05\/logo-wheelsem.png","contentUrl":"https:\/\/wheelsem.com\/wp-content\/uploads\/2024\/05\/logo-wheelsem.png","width":1180,"height":643,"caption":"Wheelsem"},"image":{"@id":"https:\/\/wheelsem.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wheelsem.com\/#\/schema\/person\/b005e81f0cf81aabbc8a84813fc7c364","name":"colosimo101@gmail.com","image":{"@type":"ImageObject","inLanguage":"uk","@id":"https:\/\/secure.gravatar.com\/avatar\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2373578a61de1ab19a4bc13d43cf6ae831cd9995374f0f2fbc76c49f92f5467b?s=96&d=mm&r=g","caption":"colosimo101@gmail.com"},"sameAs":["https:\/\/wheelsem.com"],"url":"https:\/\/wheelsem.com\/uk\/author\/colosimo101gmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/wheelsem.com\/uk\/wp-json\/wp\/v2\/posts\/18366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wheelsem.com\/uk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wheelsem.com\/uk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wheelsem.com\/uk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wheelsem.com\/uk\/wp-json\/wp\/v2\/comments?post=18366"}],"version-history":[{"count":4,"href":"https:\/\/wheelsem.com\/uk\/wp-json\/wp\/v2\/posts\/18366\/revisions"}],"predecessor-version":[{"id":18900,"href":"https:\/\/wheelsem.com\/uk\/wp-json\/wp\/v2\/posts\/18366\/revisions\/18900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wheelsem.com\/uk\/wp-json\/wp\/v2\/media\/18480"}],"wp:attachment":[{"href":"https:\/\/wheelsem.com\/uk\/wp-json\/wp\/v2\/media?parent=18366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wheelsem.com\/uk\/wp-json\/wp\/v2\/categories?post=18366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wheelsem.com\/uk\/wp-json\/wp\/v2\/tags?post=18366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}